{"id":530,"count":1,"description":"","link":"https:\/\/nicholasidoko.com\/blog\/tag\/what-is-a-smart-contract-in-blockchain\/","name":"What is a Smart Contract in Blockchain","slug":"what-is-a-smart-contract-in-blockchain","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>What is a Smart Contract in Blockchain<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nicholasidoko.com\/blog\/tag\/what-is-a-smart-contract-in-blockchain\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"What is a Smart Contract in Blockchain\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nicholasidoko.com\/blog\/tag\/what-is-a-smart-contract-in-blockchain\/\" \/>\n<meta property=\"og:site_name\" content=\"Nicholas Idoko\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@nitechnologies\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/nicholasidoko.com\\\/blog\\\/tag\\\/what-is-a-smart-contract-in-blockchain\\\/\",\"url\":\"https:\\\/\\\/nicholasidoko.com\\\/blog\\\/tag\\\/what-is-a-smart-contract-in-blockchain\\\/\",\"name\":\"What is a Smart Contract in Blockchain\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nicholasidoko.com\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nicholasidoko.com\\\/blog\\\/tag\\\/what-is-a-smart-contract-in-blockchain\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nicholasidoko.com\\\/blog\\\/tag\\\/what-is-a-smart-contract-in-blockchain\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nicholasidoko.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"What is a Smart Contract in Blockchain\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nicholasidoko.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/nicholasidoko.com\\\/blog\\\/\",\"name\":\"Nicholas Idoko\",\"description\":\"Web, App &amp; Custom Software Company\",\"publisher\":{\"@id\":\"https:\\\/\\\/nicholasidoko.com\\\/blog\\\/#organization\"},\"alternateName\":\"Nicholas Idoko\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nicholasidoko.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nicholasidoko.com\\\/blog\\\/#organization\",\"name\":\"Nicholas Idoko\",\"url\":\"https:\\\/\\\/nicholasidoko.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/nicholasidoko.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/nicholasidoko.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/NIT-logo-1.jpg\",\"contentUrl\":\"https:\\\/\\\/nicholasidoko.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/NIT-logo-1.jpg\",\"width\":600,\"height\":600,\"caption\":\"Nicholas Idoko\"},\"image\":{\"@id\":\"https:\\\/\\\/nicholasidoko.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/nitechnologies\",\"https:\\\/\\\/www.instagram.com\\\/nitechnologies\\\/\",\"https:\\\/\\\/youtube.com\\\/channel\\\/UCdJpZYQ5OkreCcmyvkGKboA\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"What is a Smart Contract in Blockchain","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nicholasidoko.com\/blog\/tag\/what-is-a-smart-contract-in-blockchain\/","og_locale":"en_US","og_type":"article","og_title":"What is a Smart Contract in Blockchain","og_url":"https:\/\/nicholasidoko.com\/blog\/tag\/what-is-a-smart-contract-in-blockchain\/","og_site_name":"Nicholas Idoko","twitter_card":"summary_large_image","twitter_site":"@nitechnologies","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/nicholasidoko.com\/blog\/tag\/what-is-a-smart-contract-in-blockchain\/","url":"https:\/\/nicholasidoko.com\/blog\/tag\/what-is-a-smart-contract-in-blockchain\/","name":"What is a Smart Contract in Blockchain","isPartOf":{"@id":"https:\/\/nicholasidoko.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/nicholasidoko.com\/blog\/tag\/what-is-a-smart-contract-in-blockchain\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/nicholasidoko.com\/blog\/tag\/what-is-a-smart-contract-in-blockchain\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nicholasidoko.com\/blog\/"},{"@type":"ListItem","position":2,"name":"What is a Smart Contract in Blockchain"}]},{"@type":"WebSite","@id":"https:\/\/nicholasidoko.com\/blog\/#website","url":"https:\/\/nicholasidoko.com\/blog\/","name":"Nicholas Idoko","description":"Web, App &amp; Custom Software Company","publisher":{"@id":"https:\/\/nicholasidoko.com\/blog\/#organization"},"alternateName":"Nicholas Idoko","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nicholasidoko.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/nicholasidoko.com\/blog\/#organization","name":"Nicholas Idoko","url":"https:\/\/nicholasidoko.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/nicholasidoko.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/nicholasidoko.com\/blog\/wp-content\/uploads\/2022\/03\/NIT-logo-1.jpg","contentUrl":"https:\/\/nicholasidoko.com\/blog\/wp-content\/uploads\/2022\/03\/NIT-logo-1.jpg","width":600,"height":600,"caption":"Nicholas Idoko"},"image":{"@id":"https:\/\/nicholasidoko.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/nitechnologies","https:\/\/www.instagram.com\/nitechnologies\/","https:\/\/youtube.com\/channel\/UCdJpZYQ5OkreCcmyvkGKboA"]}]}},"_links":{"self":[{"href":"https:\/\/nicholasidoko.com\/blog\/wp-json\/wp\/v2\/tags\/530","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nicholasidoko.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/nicholasidoko.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/nicholasidoko.com\/blog\/wp-json\/wp\/v2\/posts?tags=530"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}